{"id":448,"count":2,"description":"","link":"https:\/\/www.trans-o-flex.com\/en\/tag\/corona-vaccine-en\/","name":"Corona vaccine","slug":"corona-vaccine-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Corona vaccine Archives - trans-o-flex<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corona vaccine Archive\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.trans-o-flex.com\/en\/tag\/corona-vaccine-en\/\" \/>\n<meta property=\"og:site_name\" content=\"trans-o-flex\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.trans-o-flex.com\/wp-content\/uploads\/hero-section.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1938\" \/>\n\t<meta property=\"og:image:height\" content=\"902\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Corona vaccine Archives - trans-o-flex","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Corona vaccine Archive","og_url":"https:\/\/www.trans-o-flex.com\/en\/tag\/corona-vaccine-en\/","og_site_name":"trans-o-flex","og_image":[{"width":1938,"height":902,"url":"https:\/\/www.trans-o-flex.com\/wp-content\/uploads\/hero-section.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.trans-o-flex.com\/en\/tag\/corona-vaccine-en\/","url":"https:\/\/www.trans-o-flex.com\/en\/tag\/corona-vaccine-en\/","name":"Corona vaccine Archives - trans-o-flex","isPartOf":{"@id":"https:\/\/www.trans-o-flex.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.trans-o-flex.com\/en\/tag\/corona-vaccine-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.trans-o-flex.com\/en\/tag\/corona-vaccine-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.trans-o-flex.com\/en\/"},{"@type":"ListItem","position":2,"name":"Corona vaccine"}]},{"@type":"WebSite","@id":"https:\/\/www.trans-o-flex.com\/en\/#website","url":"https:\/\/www.trans-o-flex.com\/en\/","name":"trans-o-flex","description":"trans-o-flex","publisher":{"@id":"https:\/\/www.trans-o-flex.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trans-o-flex.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Organization","Place"],"@id":"https:\/\/www.trans-o-flex.com\/en\/#organization","name":"trans-o-flex Express GmbH & Co KGaA","url":"https:\/\/www.trans-o-flex.com\/en\/","logo":{"@id":"https:\/\/www.trans-o-flex.com\/en\/tag\/corona-vaccine-en\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.trans-o-flex.com\/en\/tag\/corona-vaccine-en\/#local-main-organization-logo"},"sameAs":["https:\/\/www.instagram.com\/transoflex\/","https:\/\/www.linkedin.com\/company\/trans-o-flex-weinheim","https:\/\/www.youtube.com\/user\/yttransoflex","https:\/\/de.wikipedia.org\/wiki\/trans-o-flex_Express","https:\/\/www.xing.com\/pages\/transoflex"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.trans-o-flex.com\/en\/tag\/corona-vaccine-en\/#local-main-organization-logo","url":"https:\/\/www.trans-o-flex.com\/wp-content\/uploads\/trans-o-flex_logo.png","contentUrl":"https:\/\/www.trans-o-flex.com\/wp-content\/uploads\/trans-o-flex_logo.png","width":567,"height":89,"caption":"trans-o-flex Express GmbH & Co KGaA"}]}},"_links":{"self":[{"href":"https:\/\/www.trans-o-flex.com\/en\/wp-json\/wp\/v2\/tags\/448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trans-o-flex.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.trans-o-flex.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.trans-o-flex.com\/en\/wp-json\/wp\/v2\/posts?tags=448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}